{"id":3355,"date":"2024-06-26T23:26:57","date_gmt":"2024-06-26T23:26:57","guid":{"rendered":"https:\/\/blackholediscos.com\/?post_type=product&#038;p=3355"},"modified":"2024-06-26T23:26:57","modified_gmt":"2024-06-26T23:26:57","slug":"nando-reis-pomar","status":"publish","type":"product","link":"https:\/\/blackholediscos.com\/en\/product\/nando-reis-pomar\/","title":{"rendered":"Nando Reis \u2013 Pomar"},"content":{"rendered":"<p>LP Lacrado e autografado pelo artista. <\/p>\n<p>\tRelic\u00e1rio \u2013 7 898194 108601<\/p>\n<p>A1\t\tAzul De Presunto<br \/>\nA2\t\tLobo Preso Em Renda<br \/>\nA3\t\tPra Onde Foi<br \/>\nB1\t\tComo Somos<br \/>\nB2\t\t\u00c1gua-Viva<br \/>\nB3\t\tPra Musa<br \/>\nB4\t\tS\u00f3 Posso Dizer (Seattle)<\/p>","protected":false},"excerpt":{"rendered":"<p>LP Lacrado e autografado pelo artista. Relic\u00e1rio \u2013 7 898194 108601 A1 Azul De Presunto A2 Lobo Preso Em Renda A3 Pra Onde Foi B1 Como Somos B2 \u00c1gua-Viva B3 Pra Musa B4 S\u00f3 Posso Dizer (Seattle)<\/p>","protected":false},"featured_media":3308,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[78,508,698,173],"product_tag":[],"artista":[752],"produtora":[753],"ano":[288],"class_list":{"0":"post-3355","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-contemporaneos","7":"product_cat-folk-rock","8":"product_cat-pop-alternativo","9":"product_cat-rock-alternativo","10":"artista-nando-reis","11":"produtora-relicario","12":"ano-288","14":"first","15":"instock","16":"shipping-taxable","17":"purchasable","18":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nando Reis \u2013 Pomar - Black Hole Discos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blackholediscos.com\/en\/product\/nando-reis-pomar\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nando Reis \u2013 Pomar - Black Hole Discos\" \/>\n<meta property=\"og:description\" content=\"LP Lacrado e autografado pelo artista. Relic\u00e1rio \u2013 7 898194 108601 A1 Azul De Presunto A2 Lobo Preso Em Renda A3 Pra Onde Foi B1 Como Somos B2 \u00c1gua-Viva B3 Pra Musa B4 S\u00f3 Posso Dizer (Seattle)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blackholediscos.com\/en\/product\/nando-reis-pomar\/\" \/>\n<meta property=\"og:site_name\" content=\"Black Hole Discos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.instagram.com\/blackholediscos\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blackholediscos.com\/wp-content\/uploads\/2024\/06\/IMG_5799-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blackholediscos.com\\\/product\\\/nando-reis-pomar\\\/\",\"url\":\"https:\\\/\\\/blackholediscos.com\\\/product\\\/nando-reis-pomar\\\/\",\"name\":\"Nando Reis \u2013 Pomar - Black Hole Discos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blackholediscos.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blackholediscos.com\\\/product\\\/nando-reis-pomar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blackholediscos.com\\\/product\\\/nando-reis-pomar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blackholediscos.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/IMG_5799-scaled.jpg\",\"datePublished\":\"2024-06-26T23:26:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blackholediscos.com\\\/product\\\/nando-reis-pomar\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blackholediscos.com\\\/product\\\/nando-reis-pomar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/blackholediscos.com\\\/product\\\/nando-reis-pomar\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blackholediscos.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/IMG_5799-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/blackholediscos.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/IMG_5799-scaled.jpg\",\"width\":2560,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blackholediscos.com\\\/product\\\/nando-reis-pomar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/blackholediscos.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/blackholediscos.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Nando Reis \u2013 Pomar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blackholediscos.com\\\/#website\",\"url\":\"https:\\\/\\\/blackholediscos.com\\\/\",\"name\":\"Black Hole Discos\",\"description\":\"Brazilian music LPs\",\"publisher\":{\"@id\":\"https:\\\/\\\/blackholediscos.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blackholediscos.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blackholediscos.com\\\/#organization\",\"name\":\"Black Hole Discos\",\"url\":\"https:\\\/\\\/blackholediscos.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/blackholediscos.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blackholediscos.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/black-hole-discos-vinis-logo.png\",\"contentUrl\":\"https:\\\/\\\/blackholediscos.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/black-hole-discos-vinis-logo.png\",\"width\":70,\"height\":66,\"caption\":\"Black Hole Discos\"},\"image\":{\"@id\":\"https:\\\/\\\/blackholediscos.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/blackholediscos\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nando Reis \u2013 Pomar - Black Hole Discos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blackholediscos.com\/en\/product\/nando-reis-pomar\/","og_locale":"en_US","og_type":"article","og_title":"Nando Reis \u2013 Pomar - Black Hole Discos","og_description":"LP Lacrado e autografado pelo artista. Relic\u00e1rio \u2013 7 898194 108601 A1 Azul De Presunto A2 Lobo Preso Em Renda A3 Pra Onde Foi B1 Como Somos B2 \u00c1gua-Viva B3 Pra Musa B4 S\u00f3 Posso Dizer (Seattle)","og_url":"https:\/\/blackholediscos.com\/en\/product\/nando-reis-pomar\/","og_site_name":"Black Hole Discos","article_publisher":"https:\/\/www.instagram.com\/blackholediscos\/","og_image":[{"width":2560,"height":2560,"url":"https:\/\/blackholediscos.com\/wp-content\/uploads\/2024\/06\/IMG_5799-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/blackholediscos.com\/product\/nando-reis-pomar\/","url":"https:\/\/blackholediscos.com\/product\/nando-reis-pomar\/","name":"Nando Reis \u2013 Pomar - Black Hole Discos","isPartOf":{"@id":"https:\/\/blackholediscos.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blackholediscos.com\/product\/nando-reis-pomar\/#primaryimage"},"image":{"@id":"https:\/\/blackholediscos.com\/product\/nando-reis-pomar\/#primaryimage"},"thumbnailUrl":"https:\/\/blackholediscos.com\/wp-content\/uploads\/2024\/06\/IMG_5799-scaled.jpg","datePublished":"2024-06-26T23:26:57+00:00","breadcrumb":{"@id":"https:\/\/blackholediscos.com\/product\/nando-reis-pomar\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blackholediscos.com\/product\/nando-reis-pomar\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/blackholediscos.com\/product\/nando-reis-pomar\/#primaryimage","url":"https:\/\/blackholediscos.com\/wp-content\/uploads\/2024\/06\/IMG_5799-scaled.jpg","contentUrl":"https:\/\/blackholediscos.com\/wp-content\/uploads\/2024\/06\/IMG_5799-scaled.jpg","width":2560,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/blackholediscos.com\/product\/nando-reis-pomar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/blackholediscos.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/blackholediscos.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Nando Reis \u2013 Pomar"}]},{"@type":"WebSite","@id":"https:\/\/blackholediscos.com\/#website","url":"https:\/\/blackholediscos.com\/","name":"Black Hole Discos","description":"Brazilian music LPs","publisher":{"@id":"https:\/\/blackholediscos.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blackholediscos.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/blackholediscos.com\/#organization","name":"Black Hole Discos","url":"https:\/\/blackholediscos.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/blackholediscos.com\/#\/schema\/logo\/image\/","url":"https:\/\/blackholediscos.com\/wp-content\/uploads\/2024\/06\/black-hole-discos-vinis-logo.png","contentUrl":"https:\/\/blackholediscos.com\/wp-content\/uploads\/2024\/06\/black-hole-discos-vinis-logo.png","width":70,"height":66,"caption":"Black Hole Discos"},"image":{"@id":"https:\/\/blackholediscos.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/blackholediscos\/"]}]}},"_links":{"self":[{"href":"https:\/\/blackholediscos.com\/en\/wp-json\/wp\/v2\/product\/3355","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blackholediscos.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/blackholediscos.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/blackholediscos.com\/en\/wp-json\/wp\/v2\/comments?post=3355"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blackholediscos.com\/en\/wp-json\/wp\/v2\/media\/3308"}],"wp:attachment":[{"href":"https:\/\/blackholediscos.com\/en\/wp-json\/wp\/v2\/media?parent=3355"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/blackholediscos.com\/en\/wp-json\/wp\/v2\/product_brand?post=3355"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/blackholediscos.com\/en\/wp-json\/wp\/v2\/product_cat?post=3355"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/blackholediscos.com\/en\/wp-json\/wp\/v2\/product_tag?post=3355"},{"taxonomy":"artista","embeddable":true,"href":"https:\/\/blackholediscos.com\/en\/wp-json\/wp\/v2\/artista?post=3355"},{"taxonomy":"produtora","embeddable":true,"href":"https:\/\/blackholediscos.com\/en\/wp-json\/wp\/v2\/produtora?post=3355"},{"taxonomy":"ano","embeddable":true,"href":"https:\/\/blackholediscos.com\/en\/wp-json\/wp\/v2\/ano?post=3355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}