{"id":637,"count":1,"description":"","link":"https:\/\/blackholediscos.com\/en\/artista\/tony-e-frankye\/","name":"tony e frankye","slug":"tony-e-frankye","taxonomy":"artista","meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arquivo de tony e frankye - Black Hole Discos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blackholediscos.com\/en\/artista\/tony-e-frankye\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arquivo de tony e frankye - Black Hole Discos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blackholediscos.com\/en\/artista\/tony-e-frankye\/\" \/>\n<meta property=\"og:site_name\" content=\"Black Hole Discos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/blackholediscos.com\\\/artista\\\/tony-e-frankye\\\/\",\"url\":\"https:\\\/\\\/blackholediscos.com\\\/artista\\\/tony-e-frankye\\\/\",\"name\":\"Arquivo de tony e frankye - Black Hole Discos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blackholediscos.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blackholediscos.com\\\/artista\\\/tony-e-frankye\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blackholediscos.com\\\/artista\\\/tony-e-frankye\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/blackholediscos.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"tony e frankye\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blackholediscos.com\\\/#website\",\"url\":\"https:\\\/\\\/blackholediscos.com\\\/\",\"name\":\"Black Hole Discos\",\"description\":\"Brazilian music LPs\",\"publisher\":{\"@id\":\"https:\\\/\\\/blackholediscos.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blackholediscos.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blackholediscos.com\\\/#organization\",\"name\":\"Black Hole Discos\",\"url\":\"https:\\\/\\\/blackholediscos.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/blackholediscos.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blackholediscos.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/black-hole-discos-vinis-logo.png\",\"contentUrl\":\"https:\\\/\\\/blackholediscos.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/black-hole-discos-vinis-logo.png\",\"width\":70,\"height\":66,\"caption\":\"Black Hole Discos\"},\"image\":{\"@id\":\"https:\\\/\\\/blackholediscos.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/blackholediscos\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arquivo de tony e frankye - Black Hole Discos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blackholediscos.com\/en\/artista\/tony-e-frankye\/","og_locale":"en_US","og_type":"article","og_title":"Arquivo de tony e frankye - Black Hole Discos","og_url":"https:\/\/blackholediscos.com\/en\/artista\/tony-e-frankye\/","og_site_name":"Black Hole Discos","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blackholediscos.com\/artista\/tony-e-frankye\/","url":"https:\/\/blackholediscos.com\/artista\/tony-e-frankye\/","name":"Arquivo de tony e frankye - Black Hole Discos","isPartOf":{"@id":"https:\/\/blackholediscos.com\/#website"},"breadcrumb":{"@id":"https:\/\/blackholediscos.com\/artista\/tony-e-frankye\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/blackholediscos.com\/artista\/tony-e-frankye\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/blackholediscos.com\/"},{"@type":"ListItem","position":2,"name":"tony e frankye"}]},{"@type":"WebSite","@id":"https:\/\/blackholediscos.com\/#website","url":"https:\/\/blackholediscos.com\/","name":"Black Hole Discos","description":"Brazilian music LPs","publisher":{"@id":"https:\/\/blackholediscos.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blackholediscos.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/blackholediscos.com\/#organization","name":"Black Hole Discos","url":"https:\/\/blackholediscos.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/blackholediscos.com\/#\/schema\/logo\/image\/","url":"https:\/\/blackholediscos.com\/wp-content\/uploads\/2024\/06\/black-hole-discos-vinis-logo.png","contentUrl":"https:\/\/blackholediscos.com\/wp-content\/uploads\/2024\/06\/black-hole-discos-vinis-logo.png","width":70,"height":66,"caption":"Black Hole Discos"},"image":{"@id":"https:\/\/blackholediscos.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/blackholediscos\/"]}]}},"_links":{"self":[{"href":"https:\/\/blackholediscos.com\/en\/wp-json\/wp\/v2\/artista\/637","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blackholediscos.com\/en\/wp-json\/wp\/v2\/artista"}],"about":[{"href":"https:\/\/blackholediscos.com\/en\/wp-json\/wp\/v2\/taxonomies\/artista"}],"wp:post_type":[{"href":"https:\/\/blackholediscos.com\/en\/wp-json\/wp\/v2\/product?artista=637"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}